{"id":15,"count":0,"description":"","link":"https:\/\/oxcollagen.lt\/it\/categoria-di-prodotto\/non-classificato\/","name":"Senza categoria","slug":"non-classificato","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uncategorized Archives - Ox collagen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oxcollagen.lt\/it\/categoria-di-prodotto\/non-classificato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uncategorized Archives - Ox collagen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oxcollagen.lt\/it\/categoria-di-prodotto\/non-classificato\/\" \/>\n<meta property=\"og:site_name\" content=\"Ox collagen\" \/>\n<meta property=\"og:image\" content=\"https:\/\/oxcollagen.lt\/wp-content\/uploads\/2024\/04\/logo_oxcollagen.lt_.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/oxcollagen.lt\\\/product-category\\\/uncategorized\\\/\",\"url\":\"https:\\\/\\\/oxcollagen.lt\\\/product-category\\\/uncategorized\\\/\",\"name\":\"Uncategorized Archives - Ox collagen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oxcollagen.lt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oxcollagen.lt\\\/product-category\\\/uncategorized\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oxcollagen.lt\\\/product-category\\\/uncategorized\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/oxcollagen.lt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uncategorized\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oxcollagen.lt\\\/#website\",\"url\":\"https:\\\/\\\/oxcollagen.lt\\\/\",\"name\":\"Ox collagen\",\"description\":\"Nat\u016bral\u016bs baton\u0117liai su kolageno baltymais\",\"publisher\":{\"@id\":\"https:\\\/\\\/oxcollagen.lt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oxcollagen.lt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oxcollagen.lt\\\/#organization\",\"name\":\"Ox collagen\",\"url\":\"https:\\\/\\\/oxcollagen.lt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/oxcollagen.lt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oxcollagen.lt\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/oxcollagen.lt_.png\",\"contentUrl\":\"https:\\\/\\\/oxcollagen.lt\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/oxcollagen.lt_.png\",\"width\":696,\"height\":696,\"caption\":\"Ox collagen\"},\"image\":{\"@id\":\"https:\\\/\\\/oxcollagen.lt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/oxcollagen\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archivi non catalogati - Collagene di bue","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oxcollagen.lt\/it\/categoria-di-prodotto\/non-classificato\/","og_locale":"it_IT","og_type":"article","og_title":"Uncategorized Archives - Ox collagen","og_url":"https:\/\/oxcollagen.lt\/it\/categoria-di-prodotto\/non-classificato\/","og_site_name":"Ox collagen","og_image":[{"width":1200,"height":675,"url":"https:\/\/oxcollagen.lt\/wp-content\/uploads\/2024\/04\/logo_oxcollagen.lt_.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/oxcollagen.lt\/product-category\/uncategorized\/","url":"https:\/\/oxcollagen.lt\/product-category\/uncategorized\/","name":"Archivi non catalogati - Collagene di bue","isPartOf":{"@id":"https:\/\/oxcollagen.lt\/#website"},"breadcrumb":{"@id":"https:\/\/oxcollagen.lt\/product-category\/uncategorized\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/oxcollagen.lt\/product-category\/uncategorized\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/oxcollagen.lt\/"},{"@type":"ListItem","position":2,"name":"Uncategorized"}]},{"@type":"WebSite","@id":"https:\/\/oxcollagen.lt\/#website","url":"https:\/\/oxcollagen.lt\/","name":"Collagene di bue","description":"Barrette naturali con proteine del collagene","publisher":{"@id":"https:\/\/oxcollagen.lt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oxcollagen.lt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/oxcollagen.lt\/#organization","name":"Collagene di bue","url":"https:\/\/oxcollagen.lt\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/oxcollagen.lt\/#\/schema\/logo\/image\/","url":"https:\/\/oxcollagen.lt\/wp-content\/uploads\/2024\/04\/oxcollagen.lt_.png","contentUrl":"https:\/\/oxcollagen.lt\/wp-content\/uploads\/2024\/04\/oxcollagen.lt_.png","width":696,"height":696,"caption":"Ox collagen"},"image":{"@id":"https:\/\/oxcollagen.lt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/oxcollagen\/"]}]}},"_links":{"self":[{"href":"https:\/\/oxcollagen.lt\/it\/wp-json\/wp\/v2\/product_cat\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oxcollagen.lt\/it\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/oxcollagen.lt\/it\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/oxcollagen.lt\/it\/wp-json\/wp\/v2\/product?product_cat=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}